{"id":24947,"date":"2022-08-03T14:27:23","date_gmt":"2022-08-03T14:27:23","guid":{"rendered":"https:\/\/acc-edu.jp\/wp-content\/uploads\/2022\/08\/7a229044543c05e5bae366ed0bb1763.jpg"},"modified":"2022-08-03T14:27:23","modified_gmt":"2022-08-03T14:27:23","slug":"7a229044543c05e5bae366ed0bb1763-2-2","status":"inherit","type":"attachment","link":"https:\/\/acc-edu.jp\/vi\/7a229044543c05e5bae366ed0bb1763-2-2\/","title":{"rendered":"7a229044543c05e5bae366ed0bb1763"},"author":1,"featured_media":0,"comment_status":"","ping_status":"closed","template":"","meta":[],"class_list":["post-24947","attachment","type-attachment","status-inherit","hentry"],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/acc-edu.jp\/wp-content\/uploads\/2022\/08\/7a229044543c05e5bae366ed0bb1763.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"534\" height=\"400\" src=\"https:\/\/acc-edu.jp\/wp-content\/uploads\/2022\/08\/7a229044543c05e5bae366ed0bb1763-534x400.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/acc-edu.jp\/wp-content\/uploads\/2022\/08\/7a229044543c05e5bae366ed0bb1763-534x400.jpg 534w, https:\/\/acc-edu.jp\/wp-content\/uploads\/2022\/08\/7a229044543c05e5bae366ed0bb1763-1067x800.jpg 1067w, https:\/\/acc-edu.jp\/wp-content\/uploads\/2022\/08\/7a229044543c05e5bae366ed0bb1763-768x576.jpg 768w, https:\/\/acc-edu.jp\/wp-content\/uploads\/2022\/08\/7a229044543c05e5bae366ed0bb1763-1536x1152.jpg 1536w, https:\/\/acc-edu.jp\/wp-content\/uploads\/2022\/08\/7a229044543c05e5bae366ed0bb1763.jpg 1702w\" sizes=\"auto, (max-width: 534px) 100vw, 534px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":1702,"height":1276,"file":"2022\/08\/7a229044543c05e5bae366ed0bb1763.jpg","sizes":{"medium":{"file":"7a229044543c05e5bae366ed0bb1763-534x400.jpg","width":534,"height":400,"mime_type":"image\/jpeg","source_url":"https:\/\/acc-edu.jp\/wp-content\/uploads\/2022\/08\/7a229044543c05e5bae366ed0bb1763-534x400.jpg"},"large":{"file":"7a229044543c05e5bae366ed0bb1763-1067x800.jpg","width":1067,"height":800,"mime_type":"image\/jpeg","source_url":"https:\/\/acc-edu.jp\/wp-content\/uploads\/2022\/08\/7a229044543c05e5bae366ed0bb1763-1067x800.jpg"},"thumbnail":{"file":"7a229044543c05e5bae366ed0bb1763-280x280.jpg","width":280,"height":280,"mime_type":"image\/jpeg","source_url":"https:\/\/acc-edu.jp\/wp-content\/uploads\/2022\/08\/7a229044543c05e5bae366ed0bb1763-280x280.jpg"},"medium_large":{"file":"7a229044543c05e5bae366ed0bb1763-768x576.jpg","width":768,"height":576,"mime_type":"image\/jpeg","source_url":"https:\/\/acc-edu.jp\/wp-content\/uploads\/2022\/08\/7a229044543c05e5bae366ed0bb1763-768x576.jpg"},"1536x1536":{"file":"7a229044543c05e5bae366ed0bb1763-1536x1152.jpg","width":1536,"height":1152,"mime_type":"image\/jpeg","source_url":"https:\/\/acc-edu.jp\/wp-content\/uploads\/2022\/08\/7a229044543c05e5bae366ed0bb1763-1536x1152.jpg"},"full":{"file":"7a229044543c05e5bae366ed0bb1763.jpg","width":1702,"height":1276,"mime_type":"image\/jpeg","source_url":"https:\/\/acc-edu.jp\/wp-content\/uploads\/2022\/08\/7a229044543c05e5bae366ed0bb1763.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":null,"source_url":"https:\/\/acc-edu.jp\/wp-content\/uploads\/2022\/08\/7a229044543c05e5bae366ed0bb1763.jpg","_links":{"self":[{"href":"https:\/\/acc-edu.jp\/vi\/wp-json\/wp\/v2\/media\/24947","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/acc-edu.jp\/vi\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/acc-edu.jp\/vi\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/acc-edu.jp\/vi\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/acc-edu.jp\/vi\/wp-json\/wp\/v2\/comments?post=24947"}]}}